{"id":35,"date":"2020-10-18T14:47:09","date_gmt":"2020-10-18T14:47:09","guid":{"rendered":"http:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2.jpg"},"modified":"2020-10-19T05:39:47","modified_gmt":"2020-10-19T05:39:47","slug":"ibomber-defense-level-6-south-east-europe-eightball-2","status":"inherit","type":"attachment","link":"https:\/\/ibomberdefense.standardof.net\/tl\/guide\/allied-campaign\/6-south-east-europe-eightball\/ibomber-defense-level-6-south-east-europe-eightball-2\/","title":{"rendered":"&#8220;iBomber Defense&#8221; &#8211; Level 6 &#8211; South East Europe: Eightball (2)"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"happyfiles_category":[14],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2.jpg'><img decoding=\"async\" width=\"512\" height=\"288\" src=\"https:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2-512x288.jpg\" class=\"attachment-medium size-medium\" alt=\"&quot;iBomber Defense&quot; - Level 6 - South East Europe: Eightball (2)\" srcset=\"https:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2-512x288.jpg 512w, https:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2-800x450.jpg 800w, https:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2-200x113.jpg 200w, https:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2-768x432.jpg 768w, https:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2-16x9.jpg 16w, https:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2.jpg 1280w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/a><\/p>\n<p>Wave 10 turret placement.<\/p>\n"},"caption":{"rendered":"<p>Wave 10 turret placement.<\/p>\n"},"alt_text":"\"iBomber Defense\" - Level 6 - South East Europe: Eightball (2)","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":720,"file":"2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2.jpg","sizes":{"medium":{"file":"iBomber-Defense-Level-6-South-East-Europe-Eightball-2-512x288.jpg","width":512,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2-512x288.jpg"},"large":{"file":"iBomber-Defense-Level-6-South-East-Europe-Eightball-2-800x450.jpg","width":800,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2-800x450.jpg"},"thumbnail":{"file":"iBomber-Defense-Level-6-South-East-Europe-Eightball-2-200x113.jpg","width":200,"height":113,"mime_type":"image\/jpeg","source_url":"https:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2-200x113.jpg"},"medium_large":{"file":"iBomber-Defense-Level-6-South-East-Europe-Eightball-2-768x432.jpg","width":768,"height":432,"mime_type":"image\/jpeg","source_url":"https:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2-768x432.jpg"},"trp-custom-language-flag":{"file":"iBomber-Defense-Level-6-South-East-Europe-Eightball-2-16x9.jpg","width":16,"height":9,"mime_type":"image\/jpeg","source_url":"https:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2-16x9.jpg"},"full":{"file":"iBomber-Defense-Level-6-South-East-Europe-Eightball-2.jpg","width":1280,"height":720,"mime_type":"image\/jpeg","source_url":"https:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":285,"source_url":"https:\/\/ibomberdefense.standardof.net\/wp-content\/uploads\/sites\/5\/2020\/10\/iBomber-Defense-Level-6-South-East-Europe-Eightball-2.jpg","_links":{"self":[{"href":"https:\/\/ibomberdefense.standardof.net\/tl\/wp-json\/wp\/v2\/media\/35"}],"collection":[{"href":"https:\/\/ibomberdefense.standardof.net\/tl\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ibomberdefense.standardof.net\/tl\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ibomberdefense.standardof.net\/tl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ibomberdefense.standardof.net\/tl\/wp-json\/wp\/v2\/comments?post=35"}],"wp:term":[{"taxonomy":"happyfiles_category","embeddable":true,"href":"https:\/\/ibomberdefense.standardof.net\/tl\/wp-json\/wp\/v2\/happyfiles_category?post=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}